{"id":37,"date":"2020-05-14T09:07:31","date_gmt":"2020-05-14T09:07:31","guid":{"rendered":"https:\/\/www.ub.edu\/longevity-institute?page_id=37"},"modified":"2022-03-11T23:57:55","modified_gmt":"2022-03-11T23:57:55","slug":"noticias","status":"publish","type":"page","link":"https:\/\/www.ub.edu\/private-pensions\/noticias\/","title":{"rendered":"Noticias"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 hundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1 fusion-builder-column-0 fusion-one-full fusion-column-first fusion-column-last 1_1\"  style='margin-top:0px;margin-bottom:20px;'><div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\">\t\t<div class=\"wppsac-wrap wppsac-slick-slider-wrp wppsac-clearfix \" data-conf=\"{&quot;dots&quot;:&quot;true&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;autoplay_interval&quot;:&quot;8000&quot;,&quot;speed&quot;:&quot;500&quot;,&quot;rtl&quot;:&quot;false&quot;,&quot;lazyload&quot;:&quot;&quot;}\">\r\n\t\t\t<div id=\"wppsac-post-slider-1\" class=\"wppsac-post-slider-init wppsac-post-slider design-3\">\r\n\t\t\t\t<div class=\"wppsac-post-slides\">\r\n\t<div class=\"wppsac-post-overlay\">\r\n\t\t<div class=\"wppsac-post-image-bg\">\r\n\t\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/08\/03\/mutualidades-de-prevision-social-alternativas-el-parlamento-decide-mucho-mas-que-su-futuro-respecto-al-reta\/\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"wppsac-post-image\"  src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/08\/cerdito_Vanguardia.jpeg\" alt=\"Mutualidades de previsi\u00f3n social alternativas: el Parlamento decide mucho m\u00e1s que su futuro respecto al RETA\" \/>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"wppsac-post-categories\"><ul class=\"wppsac-post-categories-list\"><li><a href=\"https:\/\/www.ub.edu\/private-pensions\/category\/destacados\/\">Destacados<\/a><\/li><li><a href=\"https:\/\/www.ub.edu\/private-pensions\/category\/noticias\/\">Noticias<\/a><\/li><li><a href=\"https:\/\/www.ub.edu\/private-pensions\/category\/prensa\/\">Prensa<\/a><\/li><\/ul><\/div>\r\n\t\t\r\n\t\t<div class=\"wppsac-post-short-content\">\r\n\t\t\t<div class=\"wppsac-item-meta bottom\">\r\n\t\t\t  \t<h2 class=\"wppsac-post-title\">\r\n\t\t\t\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/08\/03\/mutualidades-de-prevision-social-alternativas-el-parlamento-decide-mucho-mas-que-su-futuro-respecto-al-reta\/\">Mutualidades de previsi\u00f3n social alternativas: el Parlamento decide mucho m\u00e1s que su futuro respecto al RETA<\/a>\r\n\t\t\t\t<\/h2>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"wppsac-post-date\">\r\n\t\t\t\t\tagosto 3, 2026\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"wppsac-post-content\">\r\n\t\t\t\t\t<div class=\"wppsac-sub-content\">La muerte de J\u00fcrgen Habermas el pasado mes de marzo cerr\u00f3 una de las trayectorias intelectuales m\u00e1s influyentes de la Europa democr\u00e1tica. Sin embargo, las grandes ideas no desaparecen con quienes las formularon. En ocasiones adquieren una actualidad inesperada. Eso sucede hoy en Espa\u00f1a con el debate parlamentario sobre el futuro de las mutualidades de previsi\u00f3n social alternativas al R\u00e9gimen Especial de Trabajadores Aut\u00f3nomos. A primera vista, podr\u00eda parecer una discusi\u00f3n reservada a juristas, actuarios y profesionales colegiados. Pero lo que est\u00e1 en juego es una cuesti\u00f3n m\u00e1s profunda: qui\u00e9n debe organizar la protecci\u00f3n social en una democracia avanzada. Debe hacerlo exclusivamente el Estado, debe confiarse al mercado o debe reconocerse un espacio propio a una sociedad civil capaz de...<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-fullwidth.fusion-builder-row-1 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link) , .fusion-fullwidth.fusion-builder-row-1 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):before, .fusion-fullwidth.fusion-builder-row-1 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):after {color: #ff9800;}.fusion-fullwidth.fusion-builder-row-1 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):hover, .fusion-fullwidth.fusion-builder-row-1 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):hover:before, .fusion-fullwidth.fusion-builder-row-1 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):hover:after {color: #607d8b;}.fusion-fullwidth.fusion-builder-row-1 .pagination a.inactive:hover, .fusion-fullwidth.fusion-builder-row-1 .fusion-filters .fusion-filter.fusion-active a {border-color: #607d8b;}.fusion-fullwidth.fusion-builder-row-1 .pagination .current {border-color: #607d8b; background-color: #607d8b;}.fusion-fullwidth.fusion-builder-row-1 .fusion-filters .fusion-filter.fusion-active a, .fusion-fullwidth.fusion-builder-row-1 .fusion-date-and-formats .fusion-format-box, .fusion-fullwidth.fusion-builder-row-1 .fusion-popover, .fusion-fullwidth.fusion-builder-row-1 .tooltip-shortcode {color: #607d8b;}#main .fusion-fullwidth.fusion-builder-row-1 .post .blog-shortcode-post-title a:hover {color: #607d8b;}<\/style><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:50px;padding-right:0px;padding-bottom:50px;padding-left:0px;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_3_4 fusion-builder-column-1 fusion-three-fourth fusion-column-first 3_4\"  style='margin-top:0px;margin-bottom:20px;width:74%; margin-right: 4%;'><div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\"><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-medium-alternate fusion-blog-infinite\"><div class=\"fusion-posts-container fusion-posts-container-infinite fusion-no-meta-info\" data-pages=\"12\"><article id=\"blog-1-post-10011\" class=\"fusion-post-medium-alternate post-10011 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">28<\/span><span class=\"fusion-month-year\">07, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/07\/28\/mutualidades-alternativas-al-reta-y-multiactividad-una-opcion-que-merece-futuro\/\" aria-label=\"Mutualidades alternativas al RETA y multiactividad: una opci\u00f3n que merece futuro\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2021\/11\/varea_vanguardia-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2021\/11\/varea_vanguardia-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2021\/11\/varea_vanguardia-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/07\/28\/mutualidades-alternativas-al-reta-y-multiactividad-una-opcion-que-merece-futuro\/\">Mutualidades alternativas al RETA y multiactividad: una opci\u00f3n que merece futuro<\/a><\/h2><div class=\"fusion-post-content-container\"><p>El debate parlamentario sobre las\u00a0<strong>mutualidades de previsi\u00f3n social alternativas al RETA<\/strong>\u00a0llega a un momento decisivo. Tras su paso por el Senado, la proposici\u00f3n de ley ha vuelto al Congreso con cambios relevantes sobre la pasarela voluntaria al sistema p\u00fablico, la conversi\u00f3n de los derechos econ\u00f3micos acumulados, la exclusi\u00f3n de los pensionistas \u2014salvo quienes perciban una pensi\u00f3n de viudedad\u2014 y el [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9983\" class=\"fusion-post-medium-alternate post-9983 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-eiopa category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">7<\/span><span class=\"fusion-month-year\">07, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/07\/07\/la-dra-merce-claramunt-participa-en-la-reunion-del-occupational-pensions-stakeholder-group-opsg-de-eiopa-centrada-en-los-nuevos-informes-sobre-prevision-social-complementaria\/\" aria-label=\"La Dra. Merc\u00e8 Claramunt participa en la reuni\u00f3n del Occupational Pensions Stakeholder Group (OPSG) de EIOPA centrada en los nuevos informes sobre previsi\u00f3n social complementaria\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/07\/imagen_eiopaN-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/07\/imagen_eiopaN-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/07\/imagen_eiopaN-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/07\/07\/la-dra-merce-claramunt-participa-en-la-reunion-del-occupational-pensions-stakeholder-group-opsg-de-eiopa-centrada-en-los-nuevos-informes-sobre-prevision-social-complementaria\/\">La Dra. Merc\u00e8 Claramunt participa en la reuni\u00f3n del Occupational Pensions Stakeholder Group (OPSG) de EIOPA centrada en los nuevos informes sobre previsi\u00f3n social complementaria<\/a><\/h2><div class=\"fusion-post-content-container\"><p>El pasado 2 de julio de 2026 se celebr\u00f3, en formato telem\u00e1tico, una nueva reuni\u00f3n del Occupational Pensions Stakeholder Group (OPSG) de la Autoridad Europea de Seguros y Pensiones de Jubilaci\u00f3n (EIOPA), en la que particip\u00f3 la Dra. Merc\u00e8 Claramunt, presidenta del Comit\u00e9 Cient\u00edfico del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria y miembro de este \u00f3rgano consultivo [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9974\" class=\"fusion-post-medium-alternate post-9974 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">6<\/span><span class=\"fusion-month-year\">07, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/07\/06\/la-jubilacion-que-viene-que-podemos-aprender-de-europa\/\" aria-label=\"La jubilaci\u00f3n que viene: qu\u00e9 podemos aprender de Europa\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/07\/imagen_vanguardia-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/07\/06\/la-jubilacion-que-viene-que-podemos-aprender-de-europa\/\">La jubilaci\u00f3n que viene: qu\u00e9 podemos aprender de Europa<\/a><\/h2><div class=\"fusion-post-content-container\"><p>En un contexto marcado por el envejecimiento de la poblaci\u00f3n, el aumento de la esperanza de vida y unas trayectorias laborales cada vez m\u00e1s heterog\u00e9neas, el debate sobre las pensiones exige una mirada m\u00e1s amplia que la centrada exclusivamente en el sistema p\u00fablico. En este art\u00edculo publicado en La Vanguardia, el Dr. Oriol Roch Casellas, miembro del Observatorio de los [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9942\" class=\"fusion-post-medium-alternate post-9942 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">19<\/span><span class=\"fusion-month-year\">06, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/06\/19\/expertos-reclaman-avanzar-hacia-un-modelo-mixto-de-prevision-social-complementaria-con-mas-negociacion-colectiva-automatismos-e-informacion-al-ciudadano\/\" aria-label=\"Expertos reclaman avanzar hacia un modelo mixto de previsi\u00f3n social complementaria con m\u00e1s negociaci\u00f3n colectiva, automatismos e informaci\u00f3n al ciudadano.\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/06\/evento_varea_oriol-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/06\/evento_varea_oriol-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/06\/evento_varea_oriol-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/06\/19\/expertos-reclaman-avanzar-hacia-un-modelo-mixto-de-prevision-social-complementaria-con-mas-negociacion-colectiva-automatismos-e-informacion-al-ciudadano\/\">Expertos reclaman avanzar hacia un modelo mixto de previsi\u00f3n social complementaria con m\u00e1s negociaci\u00f3n colectiva, automatismos e informaci\u00f3n al ciudadano.<\/a><\/h2><div class=\"fusion-post-content-container\"><p>El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria ha celebrado hoy el webinar de presentaci\u00f3n de las conclusiones del II Seminario Europeo sobre Previsi\u00f3n Social Complementaria, organizado en el marco de actividades del Aula UB-VidaCaixa de Previsi\u00f3n Social. El encuentro ha reunido a representantes institucionales, expertos acad\u00e9micos, sector asegurador y agentes sociales para analizar las recomendaciones publicadas por [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9922\" class=\"fusion-post-medium-alternate post-9922 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">2<\/span><span class=\"fusion-month-year\">06, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/06\/02\/fallados-los-premios-de-educacion-financiera-en-redes-sociales-de-actual-360-en-su-segunda-edicion\/\" aria-label=\"Fallados los Premios de Educaci\u00f3n Financiera en Redes Sociales de Actual 360 en su segunda edici\u00f3n\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/06\/premio_fondo-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/06\/premio_fondo-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/06\/premio_fondo-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/06\/02\/fallados-los-premios-de-educacion-financiera-en-redes-sociales-de-actual-360-en-su-segunda-edicion\/\">Fallados los Premios de Educaci\u00f3n Financiera en Redes Sociales de Actual 360 en su segunda edici\u00f3n<\/a><\/h2><div class=\"fusion-post-content-container\"><p data-start=\"102\" data-end=\"540\">La Asociaci\u00f3n Actual 360 y el Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria han resuelto la segunda edici\u00f3n del <strong data-start=\"241\" data-end=\"293\">Premio de Educaci\u00f3n Financiera en Redes Sociales<\/strong>, una iniciativa dirigida a fomentar entre los estudiantes universitarios la divulgaci\u00f3n de contenidos relacionados con las finanzas, los seguros y la previsi\u00f3n social mediante formatos audiovisuales adaptados a [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9900\" class=\"fusion-post-medium-alternate post-9900 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">28<\/span><span class=\"fusion-month-year\">05, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/28\/actual360-y-el-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria-impulsan-el-talento-joven-en-educacion-financiera-a-traves-de-las-redes-sociales\/\" aria-label=\"Actual360 y el observatorio de los sistemas europeos de previsi\u00f3n social complementaria impulsan el talento joven en educaci\u00f3n financiera a trav\u00e9s de las redes sociales.\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/segundos_premios-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/segundos_premios-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/segundos_premios-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/28\/actual360-y-el-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria-impulsan-el-talento-joven-en-educacion-financiera-a-traves-de-las-redes-sociales\/\">Actual360 y el observatorio de los sistemas europeos de previsi\u00f3n social complementaria impulsan el talento joven en educaci\u00f3n financiera a trav\u00e9s de las redes sociales.<\/a><\/h2><div class=\"fusion-post-content-container\"><p>La segunda edici\u00f3n del Premio de Educaci\u00f3n Financiera en Redes Sociales ha reconocido los mejores v\u00eddeos divulgativos sobre Finanzas, Seguros y Previsi\u00f3n Social.<br>\nAlcal\u00e1 de Henares, 28, mayo de 2026. La Asociaci\u00f3n Actual360 y el Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria de la Universidad de Barcelona han convocado la segunda edici\u00f3n del Premio de Educaci\u00f3n Financiera en Redes [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9892\" class=\"fusion-post-medium-alternate post-9892 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">28<\/span><span class=\"fusion-month-year\">05, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/28\/el-aula-ub-aon-de-economia-del-comportamiento-impulsa-la-investigacion-la-formacion-y-la-innovacion-en-el-ahorro-para-la-jubilacion\/\" aria-label=\"El Aula UB-Aon de econom\u00eda del comportamiento impulsa la investigaci\u00f3n, la formaci\u00f3n y la innovaci\u00f3n en el ahorro para la jubilaci\u00f3n.\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/imagen_evento-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/imagen_evento-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/imagen_evento-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/28\/el-aula-ub-aon-de-economia-del-comportamiento-impulsa-la-investigacion-la-formacion-y-la-innovacion-en-el-ahorro-para-la-jubilacion\/\">El Aula UB-Aon de econom\u00eda del comportamiento impulsa la investigaci\u00f3n, la formaci\u00f3n y la innovaci\u00f3n en el ahorro para la jubilaci\u00f3n.<\/a><\/h2><div class=\"fusion-post-content-container\"><p>La Universidad de Barcelona celebra una masterclass en formato webinar sobre c\u00f3mo la econom\u00eda del comportamiento est\u00e1 redefiniendo la previsi\u00f3n social complementaria<\/p>\n<p>Barcelona, 27 de mayo de 2026.\u2013 El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria de la Universidad de Barcelona ha celebrado la masterclass en formato webinar \u201cC\u00f3mo la econom\u00eda del comportamiento est\u00e1 redefiniendo el ahorro para la [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9889\" class=\"fusion-post-medium-alternate post-9889 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">21<\/span><span class=\"fusion-month-year\">05, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/21\/la-iv-asamblea-del-observatorio-apuesta-por-aplicar-en-espana-las-recomendaciones-de-la-comision-europea-y-desarrollar-el-indice-de-desarrollo-financiero-personal\/\" aria-label=\"La IV Asamblea del Observatorio apuesta por aplicar en Espa\u00f1a las recomendaciones de la Comisi\u00f3n Europea y desarrollar el \u00cdndice de Desarrollo Financiero Personal\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/4asambleageneral-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/4asambleageneral-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/4asambleageneral-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/21\/la-iv-asamblea-del-observatorio-apuesta-por-aplicar-en-espana-las-recomendaciones-de-la-comision-europea-y-desarrollar-el-indice-de-desarrollo-financiero-personal\/\">La IV Asamblea del Observatorio apuesta por aplicar en Espa\u00f1a las recomendaciones de la Comisi\u00f3n Europea y desarrollar el \u00cdndice de Desarrollo Financiero Personal<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Barcelona, 21 de mayo de 2026 | 12:00 h (streaming). \u2013 La IV Asamblea del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria de la Universidad de Barcelona se ha celebrado por streaming como reuni\u00f3n general de su comunidad de partenaires, formada por m\u00e1s de 60 entidades entre patrocinadores y colaboradores, la red de 21 universidades europeas y 40 [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9885\" class=\"fusion-post-medium-alternate post-9885 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">15<\/span><span class=\"fusion-month-year\">05, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/15\/el-aula-ub-vidacaixa-de-prevision-social-acerca-el-sector-asegurador-a-los-estudiantes-de-ade-de-la-universidad-de-barcelona\/\" aria-label=\"El Aula UB-VidaCaixa de Previsi\u00f3n Social acerca el sector asegurador a los estudiantes de ADE de la Universidad de Barcelona.\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/imagen_noticia_26_05-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/imagen_noticia_26_05-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/05\/imagen_noticia_26_05-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/05\/15\/el-aula-ub-vidacaixa-de-prevision-social-acerca-el-sector-asegurador-a-los-estudiantes-de-ade-de-la-universidad-de-barcelona\/\">El Aula UB-VidaCaixa de Previsi\u00f3n Social acerca el sector asegurador a los estudiantes de ADE de la Universidad de Barcelona.<\/a><\/h2><div class=\"fusion-post-content-container\"><p>La iniciativa refuerza su compromiso con la formaci\u00f3n, la investigaci\u00f3n y la transferencia de conocimiento en el \u00e1mbito de la previsi\u00f3n social complementaria.<\/p>\n<p>El Aula UB-VidaCaixa de Previsi\u00f3n Social, en colaboraci\u00f3n con el Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria, celebr\u00f3 una sesi\u00f3n de presentaci\u00f3n dirigida a estudiantes de cuarto curso del grado de Administraci\u00f3n y Direcci\u00f3n de Empresas [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9828\" class=\"fusion-post-medium-alternate post-9828 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">24<\/span><span class=\"fusion-month-year\">04, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/24\/la-dra-merce-claramunt-aporta-la-vision-de-eiopa-en-la-aae-spring-meeting-2026\/\" aria-label=\"LA DRA. MERC\u00c8 CLARAMUNT APORTA LA VISI\u00d3N DE EIOPA EN LA AAE SPRING MEETING 2026\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/mclaramunt_ub_aae-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/mclaramunt_ub_aae-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/mclaramunt_ub_aae-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/24\/la-dra-merce-claramunt-aporta-la-vision-de-eiopa-en-la-aae-spring-meeting-2026\/\">LA DRA. MERC\u00c8 CLARAMUNT APORTA LA VISI\u00d3N DE EIOPA EN LA AAE SPRING MEETING 2026<\/a><\/h2><div class=\"fusion-post-content-container\"><p>La AAE Spring Meeting 2026, celebrada los d\u00edas 23 y 24 de abril, reuni\u00f3 a los principales comit\u00e9s de la Actuarial Association of Europe (AAE) para avanzar en iniciativas estrat\u00e9gicas en educaci\u00f3n actuarial, sostenibilidad y pensiones, en un momento clave de evoluci\u00f3n de la profesi\u00f3n en Europa.<\/p>\n<p>Entre las participaciones m\u00e1s relevantes destaca la de la Dra. Merc\u00e8 Claramunt, catedr\u00e1tica de [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9824\" class=\"fusion-post-medium-alternate post-9824 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">18<\/span><span class=\"fusion-month-year\">04, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/18\/mutualidades-alternativas-al-reta-un-debate-fiscal-donde-el-gasto-evitado-pesa-mas-que-la-recaudacion-perdida\/\" aria-label=\"Mutualidades alternativas al RETA: un debate fiscal donde el gasto evitado pesa m\u00e1s que la recaudaci\u00f3n perdida\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/grafimoneda-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/grafimoneda-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/grafimoneda-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/18\/mutualidades-alternativas-al-reta-un-debate-fiscal-donde-el-gasto-evitado-pesa-mas-que-la-recaudacion-perdida\/\">Mutualidades alternativas al RETA: un debate fiscal donde el gasto evitado pesa m\u00e1s que la recaudaci\u00f3n perdida<\/a><\/h2><div class=\"fusion-post-content-container\"><p>En un contexto de creciente presi\u00f3n sobre la sostenibilidad del sistema p\u00fablico de pensiones, el debate sobre las mutualidades de previsi\u00f3n social alternativas al RETA suele centrarse en la recaudaci\u00f3n que dejan de aportar. En este art\u00edculo, el Dr. Javier Varea, director del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria, analiza la cuesti\u00f3n desde una perspectiva fiscal m\u00e1s [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9818\" class=\"fusion-post-medium-alternate post-9818 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">11<\/span><span class=\"fusion-month-year\">04, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/11\/las-matematicas-que-sostienen-las-finanzas-del-futuro-se-citan-en-el-crm\/\" aria-label=\"Las matem\u00e1ticas que sostienen las finanzas del futuro se citan en el CRM\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/MAF-2026_tr-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/MAF-2026_tr-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/MAF-2026_tr-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/11\/las-matematicas-que-sostienen-las-finanzas-del-futuro-se-citan-en-el-crm\/\">Las matem\u00e1ticas que sostienen las finanzas del futuro se citan en el CRM<\/a><\/h2><div class=\"fusion-post-content-container\"><p>El congreso internacional MAF 2026 re\u00fane en Barcelona a expertos en ciencia actuarial y finanzas<\/p>\n<p>El Centre de Recerca Matem\u00e0tica (CRM) ha acogido, del 8 al 10 de abril de 2026, el Congreso Internacional MAF 2026, dedicado a la aplicaci\u00f3n de m\u00e9todos matem\u00e1ticos y estad\u00edsticos en las ciencias actuariales y las finanzas, con participaci\u00f3n de especialistas procedentes de instituciones acad\u00e9micas y [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9809\" class=\"fusion-post-medium-alternate post-9809 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">1<\/span><span class=\"fusion-month-year\">04, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/01\/la-dra-merce-claramunt-lidera-en-la-eiopa-el-analisis-sobre-la-aversion-al-riesgo-en-los-planes-de-pensiones\/\" aria-label=\"La Dra. Merc\u00e8 Claramunt lidera en la EIOPA el an\u00e1lisis sobre la aversi\u00f3n al riesgo en los planes de pensiones\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/Westhafen-Tower-320x202.png\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/Westhafen-Tower-320x202.png 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/04\/Westhafen-Tower-700x441.png 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/04\/01\/la-dra-merce-claramunt-lidera-en-la-eiopa-el-analisis-sobre-la-aversion-al-riesgo-en-los-planes-de-pensiones\/\">La Dra. Merc\u00e8 Claramunt lidera en la EIOPA el an\u00e1lisis sobre la aversi\u00f3n al riesgo en los planes de pensiones<\/a><\/h2><div class=\"fusion-post-content-container\"><p><strong>Frankfurt am Main\u2013 El pasado lunes 23 de marzo, la Autoridad Europea de Seguros y Pensiones de Jubilaci\u00f3n (EIOPA) celebr\u00f3 una jornada clave que reuni\u00f3 al Occupational Pensions Stakeholder Group (OPSG) y a su Junta de Supervisores (Board of Supervisors \u2013 BoS).<\/strong><\/p>\n<p>En este escenario de alto nivel regulador, la Dra. Merc\u00e8 Claramunt, presidenta del Comit\u00e9 Cient\u00edfico del Observatorio de los [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9801\" class=\"fusion-post-medium-alternate post-9801 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">26<\/span><span class=\"fusion-month-year\">03, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/26\/aprobada-la-memoria-de-actividades-2025-y-el-plan-de-accion-2026-del-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria\/\" aria-label=\"Aprobada la memoria de actividades 2025 y el plan de acci\u00f3n 2026 del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/20260326-CD-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/20260326-CD-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/20260326-CD-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/26\/aprobada-la-memoria-de-actividades-2025-y-el-plan-de-accion-2026-del-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria\/\">Aprobada la memoria de actividades 2025 y el plan de acci\u00f3n 2026 del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Celebrado el Consejo de Direcci\u00f3n del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria, \u00f3rgano colectivo de direcci\u00f3n de esta estructura de la Universidad de Barcelona, que reune a los representantes de los distintos \u00e1mbitos acad\u00e9micos y a los representantes del Consejo Asesor, integrado por sus partenaires. Las principales funciones de dicho \u00f3rgano es la aprobaci\u00f3n de la memoria [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9796\" class=\"fusion-post-medium-alternate post-9796 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">23<\/span><span class=\"fusion-month-year\">03, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/23\/hablar-de-dinero-es-de-buena-educacion-por-merche-galisteo\/\" aria-label=\"Hablar de dinero es de buena educaci\u00f3n. Por Merche Galisteo\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/imagen_clase-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/imagen_clase-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/imagen_clase-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/23\/hablar-de-dinero-es-de-buena-educacion-por-merche-galisteo\/\">Hablar de dinero es de buena educaci\u00f3n. Por Merche Galisteo<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Merche Galisteo, coordinadora del \u00c1rea de Educaci\u00f3n Financiera del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria, publica un nuevo art\u00edculo en La Vanguardia en el que reflexiona sobre la importancia de hablar de dinero como un acto de buena educaci\u00f3n. En su an\u00e1lisis, la autora subraya que, pese al impacto directo que las decisiones financieras tienen en la [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9763\" class=\"fusion-post-medium-alternate post-9763 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">10<\/span><span class=\"fusion-month-year\">03, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/10\/el-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria-participo-en-la-audiencia-publica-del-comite-economico-y-social-europeo-sobre-pensiones-complementarias-en-beneficio-de-la-c\/\" aria-label=\"El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria particip\u00f3 en la audiencia p\u00fablica del Comit\u00e9 Econ\u00f3mico y Social Europeo sobre Pensiones complementarias en beneficio de la ciudadan\u00eda de la UE\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/20260310-320x202.png\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/20260310-320x202.png 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/20260310-700x441.png 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/10\/el-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria-participo-en-la-audiencia-publica-del-comite-economico-y-social-europeo-sobre-pensiones-complementarias-en-beneficio-de-la-c\/\">El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria particip\u00f3 en la audiencia p\u00fablica del Comit\u00e9 Econ\u00f3mico y Social Europeo sobre Pensiones complementarias en beneficio de la ciudadan\u00eda de la UE<\/a><\/h2><div class=\"fusion-post-content-container\"><p><strong>Bruselas (<em>online<\/em>), 10 de marzo de 2026 \u2014 El Comit\u00e9 Econ\u00f3mico y Social Europeo (CESE) celebr\u00f3 la audiencia p\u00fablica \u201cPensiones complementarias en beneficio de la ciudadan\u00eda de la UE (Supplementary pensions to the benefit of EU citizens)\u201d, donde se debati\u00f3 c\u00f3mo los reg\u00edmenes ocupacionales y privados pod\u00edan mejorar la adecuaci\u00f3n de las pensiones y aportar capital a largo plazo a [\u2026]<\/strong><\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9744\" class=\"fusion-post-medium-alternate post-9744 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">5<\/span><span class=\"fusion-month-year\">03, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/05\/9744\/\" aria-label=\"El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria re\u00fane a expertos para abordar pensiones, cuidados y Silver Economy con motivo del D\u00eda de la Mujer\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/webinar_longevidad-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/webinar_longevidad-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/03\/webinar_longevidad-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/03\/05\/9744\/\">El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria re\u00fane a expertos para abordar pensiones, cuidados y Silver Economy con motivo del D\u00eda de la Mujer<\/a><\/h2><div class=\"fusion-post-content-container\"><p><strong>Barcelona, 5 de marzo de 2026 \u2014 Con motivo de la celebraci\u00f3n del D\u00eda Internacional de la Mujer, el Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria organiz\u00f3 el webinar \u201cLa longevidad desde una perspectiva de g\u00e9nero\u201d, en colaboraci\u00f3n con Helvetia Caser y PENSIUM. La sesi\u00f3n analiz\u00f3 c\u00f3mo la mayor esperanza de vida de las mujeres, unida a trayectorias [\u2026]<\/strong><\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9713\" class=\"fusion-post-medium-alternate post-9713 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">26<\/span><span class=\"fusion-month-year\">02, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/02\/26\/el-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria-participa-en-la-asamblea-de-la-red-de-colaboradores-del-plan-finanzas-para-todos\/\" aria-label=\"El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria participa en la Asamblea de la Red de Colaboradores del Plan \u201cFinanzas para Todos\u201d\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/5APEF-26-5-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/5APEF-26-5-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/5APEF-26-5-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/02\/26\/el-observatorio-de-los-sistemas-europeos-de-prevision-social-complementaria-participa-en-la-asamblea-de-la-red-de-colaboradores-del-plan-finanzas-para-todos\/\">El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria participa en la Asamblea de la Red de Colaboradores del Plan \u201cFinanzas para Todos\u201d<\/a><\/h2><div class=\"fusion-post-content-container\"><p><strong>Madrid, 23 de febrero de 2026 \u2014 El Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria ha participado en la Asamblea de la Red de Colaboradores del Plan de Educaci\u00f3n Financiera \u201cFinanzas para Todos\u201d, celebrada en Madrid el pasado 23 de febrero.<\/strong><\/p>\n<p>En representaci\u00f3n del Observatorio asistieron su director, el Dr. Xavier Varea, y el director de Relaciones Institucionales, Jordi [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9690\" class=\"fusion-post-medium-alternate post-9690 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">23<\/span><span class=\"fusion-month-year\">02, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/02\/23\/el-observatorio-realiza-el-iv-stage-de-investigacion-centrado-en-la-educacion-financiera-y-el-impulso-de-la-prevision-social-complementaria\/\" aria-label=\"El Observatorio realiza el IV stage de investigaci\u00f3n centrado en la educaci\u00f3n financiera y el impulso de la previsi\u00f3n social complementaria\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/STAGE-DE-INVESTIGACION-320x202.jpeg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/STAGE-DE-INVESTIGACION-320x202.jpeg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/STAGE-DE-INVESTIGACION-700x441.jpeg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/02\/23\/el-observatorio-realiza-el-iv-stage-de-investigacion-centrado-en-la-educacion-financiera-y-el-impulso-de-la-prevision-social-complementaria\/\">El Observatorio realiza el IV stage de investigaci\u00f3n centrado en la educaci\u00f3n financiera y el impulso de la previsi\u00f3n social complementaria<\/a><\/h2><div class=\"fusion-post-content-container\"><p><strong>Barcelona, 22 de febrero de 2026 <\/strong><strong>\u2014<\/strong> <strong>El Observatorio ha celebrado su IV stage de investigaci\u00f3n, que tuvo como elemento central la elaboraci\u00f3n del \u00cdndice de Desarrollo Financiero (IDF), una herramienta innovadora destinada a medir de forma integral el nivel de desarrollo financiero de la ciudadan\u00eda y su impacto en el impulso de la previsi\u00f3n social complementaria.<\/strong><\/p>\n<p>Este nuevo \u00edndice se [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<article id=\"blog-1-post-9414\" class=\"fusion-post-medium-alternate post-9414 post type-post status-publish format-standard has-post-thumbnail hentry category-destacados category-noticias\">\n<div class=\"fusion-date-and-formats\"><div class=\"fusion-date-box updated\"><span class=\"fusion-date\">4<\/span><span class=\"fusion-month-year\">02, 2026<\/span><\/div><div class=\"fusion-format-box\"><i class=\"fusion-icon-pen\"><\/i><\/div><\/div>\t<style type=\"text\/css\">\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t\t<\/style>\n\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n\n<div  class=\"fusion-image-wrapper fusion-image-size-fixed\" aria-haspopup=\"true\">\n\t\n\t\n\t\t<a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/02\/04\/europa-avala-el-modelo-mutualista-alternativo-al-reta-para-los-profesionales\/\" aria-label=\"Europa avala el modelo mutualista alternativo al RETA para los profesionales\">\n\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"202\" src=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/seguros-news-articulo-mutualidades-320x202.jpg\" class=\"attachment-blog-medium size-blog-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/seguros-news-articulo-mutualidades-320x202.jpg 320w, https:\/\/www.ub.edu\/private-pensions\/wp-content\/uploads\/2026\/02\/seguros-news-articulo-mutualidades-700x441.jpg 700w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>\n\t\n\n\t\t<\/a>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/www.ub.edu\/private-pensions\/2026\/02\/04\/europa-avala-el-modelo-mutualista-alternativo-al-reta-para-los-profesionales\/\">Europa avala el modelo mutualista alternativo al RETA para los profesionales<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Jordi Gim\u00e9nez, responsable de Relaciones Institucionales del Observatorio de los Sistemas Europeos de Previsi\u00f3n Social Complementaria, publica un nuevo art\u00edculo en SegurosNews en el que se analiza el respaldo europeo al modelo de mutualidades alternativas al RETA. En el actual proceso de revisi\u00f3n normativa, tanto el an\u00e1lisis comparado del Observatorio como la posici\u00f3n de la Comisi\u00f3n Europea coinciden en se\u00f1alar [\u2026]<\/p>\n<\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/article>\n<\/div><div class=\"fusion-infinite-scroll-trigger\"><\/div><div class=\"pagination infinite-scroll clearfix\" style=\"display:none;\"><span class=\"current\">1<\/span><a href=\"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/pages\/37\/page\/2\/\" class=\"inactive\">2<\/a><a class=\"pagination-next\" href=\"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/pages\/37\/page\/2\/\"><span class=\"page-text\">Siguiente<\/span><span class=\"page-next\"><\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_4 fusion-builder-column-2 fusion-one-fourth fusion-column-last 1_4\"  style='margin-top:0px;margin-bottom:20px;width:22%'><div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\"><div class=\"fusion-search-element fusion-search-form-classic\">\t\t<form role=\"search\" class=\"searchform fusion-search-form  fusion-live-search fusion-search-form-classic\" method=\"get\" action=\"https:\/\/www.ub.edu\/private-pensions\/\">\n\t\t\t<div class=\"fusion-search-form-content\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"fusion-search-field search-field\">\n\t\t\t\t\t<label><span class=\"screen-reader-text\">Buscar:<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"search\" class=\"s fusion-live-search-input\" name=\"s\" id=\"fusion-live-search-input\" autocomplete=\"off\" placeholder=\"Buscar\" required aria-required=\"true\" aria-label=\"\"\/>\n\t\t\t\t\t\t\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"fusion-search-button search-button\">\n\t\t\t\t\t<input type=\"submit\" class=\"fusion-search-submit searchsubmit\" value=\"&#xf002;\" \/>\n\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-slider-loading\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<input type=\"hidden\" name=\"post_type[]\" value=\"post\" \/><input type=\"hidden\" name=\"fs\" value=\"1\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t<div class=\"fusion-search-results-wrapper\"><div class=\"fusion-search-results\"><\/div><\/div>\n\t\t\t\n\t\t<\/form>\n\t\t<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep sep-none\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-fullwidth.fusion-builder-row-2 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link) , .fusion-fullwidth.fusion-builder-row-2 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):before, .fusion-fullwidth.fusion-builder-row-2 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):after {color: #ff9800;}.fusion-fullwidth.fusion-builder-row-2 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):hover, .fusion-fullwidth.fusion-builder-row-2 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):hover:before, .fusion-fullwidth.fusion-builder-row-2 a:not(.fusion-button):not(.fusion-builder-module-control):not(.fusion-social-network-icon):not(.fb-icon-element):not(.fusion-countdown-link):not(.fusion-rollover-link):not(.fusion-rollover-gallery):not(.fusion-button-bar):not(.add_to_cart_button):not(.show_details_button):not(.product_type_external):not(.fusion-quick-view):not(.fusion-rollover-title-link):not(.fusion-breadcrumb-link):hover:after {color: #000000;}.fusion-fullwidth.fusion-builder-row-2 .pagination a.inactive:hover, .fusion-fullwidth.fusion-builder-row-2 .fusion-filters .fusion-filter.fusion-active a {border-color: #000000;}.fusion-fullwidth.fusion-builder-row-2 .pagination .current {border-color: #000000; background-color: #000000;}.fusion-fullwidth.fusion-builder-row-2 .fusion-filters .fusion-filter.fusion-active a, .fusion-fullwidth.fusion-builder-row-2 .fusion-date-and-formats .fusion-format-box, .fusion-fullwidth.fusion-builder-row-2 .fusion-popover, .fusion-fullwidth.fusion-builder-row-2 .tooltip-shortcode {color: #000000;}#main .fusion-fullwidth.fusion-builder-row-2 .post .blog-shortcode-post-title a:hover {color: #000000;}<\/style><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-37","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/pages\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":38,"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/pages\/37\/revisions"}],"predecessor-version":[{"id":3210,"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/pages\/37\/revisions\/3210"}],"wp:attachment":[{"href":"https:\/\/www.ub.edu\/private-pensions\/wp-json\/wp\/v2\/media?parent=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}